{"id":4885,"date":"2023-03-14T10:57:39","date_gmt":"2023-03-14T09:57:39","guid":{"rendered":"https:\/\/www.fotovol.cat\/?post_type=servei&#038;p=4885"},"modified":"2026-01-27T21:28:28","modified_gmt":"2026-01-27T20:28:28","slug":"punts-de-recarrega-per-a-vehicles-electrics","status":"publish","type":"servei","link":"https:\/\/fotovol.com\/ca\/servei\/punts-de-recarrega-per-a-vehicles-electrics\/","title":{"rendered":"Punts de rec\u00e0rrega VE"},"content":{"rendered":"\r\n<p class=\"p1\">Cada cop s\u00f3n m\u00e9s les fam\u00edlies i empreses que incorporen vehicles el\u00e8ctrics a la seva flota. En aquests casos, \u00e9s molt recomanable tenir instal\u00b7lat un o\u00a0varis\u00a0punts de rec\u00e0rrega. Aix\u00ed, podreu <b>assegurar la rec\u00e0rrega el vehicle durant les hores de treball o de descans<\/b> i donar m\u00e9s estabilitat a la vostra mobilitat.<br \/><br \/>I si a m\u00e9s es disposa de panells solars, existeix la possibilitat de transportar l&#8217;energia generada pel sistema fotovoltaic directament al punt de rec\u00e0rrega.\u00a0\u00c9s m\u00e9s, el punt de rec\u00e0rrega es pot configurar de manera que el vehicle el\u00e8ctric es recarregui \u00fanicament <b>aprofitant els excedents del sistema fotovoltaic<\/b>, fent que la instal\u00b7laci\u00f3 fotovoltaica s&#8217;aprofiti al m\u00e0xim.<\/p>\r\n","protected":false},"featured_media":7870,"template":"","class_list":["post-4885","servei","type-servei","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/fotovol.com\/ca\/wp-json\/wp\/v2\/servei\/4885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fotovol.com\/ca\/wp-json\/wp\/v2\/servei"}],"about":[{"href":"https:\/\/fotovol.com\/ca\/wp-json\/wp\/v2\/types\/servei"}],"version-history":[{"count":0,"href":"https:\/\/fotovol.com\/ca\/wp-json\/wp\/v2\/servei\/4885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fotovol.com\/ca\/wp-json\/wp\/v2\/media\/7870"}],"wp:attachment":[{"href":"https:\/\/fotovol.com\/ca\/wp-json\/wp\/v2\/media?parent=4885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}